{"id":34250,"date":"2023-04-14T03:05:45","date_gmt":"2023-04-14T07:05:45","guid":{"rendered":"https:\/\/chantnow.com\/?p=34250"},"modified":"2023-04-14T03:19:15","modified_gmt":"2023-04-14T07:19:15","slug":"the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head","status":"publish","type":"post","link":"https:\/\/chantnow.com\/es\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/","title":{"rendered":"La verdad sobre ser espiritual pero no religioso: todo est\u00e1 en tu cabeza"},"content":{"rendered":"<p>\"Dios y el diablo caminaban un d\u00eda por un sendero cuando Dios vio algo que brillaba al lado del camino. Recogi\u00e9ndolo y admirando la sustancia, Dios dijo,<\/p>\n\n\n\n<p>\"Ah, Verdad,\"<br>A lo que el diablo respondi\u00f3,<\/p>\n\n\n\n<p>\"Toma, d\u00e1melo... yo lo organizar\u00e9\".<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La religi\u00f3n se ve a menudo como normas y reglamentos r\u00edgidos que poco hacen para expresar el \u00e9xtasis de la revelaci\u00f3n espiritual, y ciertamente los rituales de una pr\u00e1ctica diaria de la religi\u00f3n deben parecer una reducci\u00f3n que se queda dr\u00e1sticamente corta de una experiencia espiritual genuina. &nbsp;<\/p>\n\n\n\n<p>Para colmo de males, las instituciones religiosas suelen estar plagadas del estigma del enga\u00f1o y la explotaci\u00f3n, degenerando en luchas por el poder, el dinero, el ego y cosas peores.<\/p>\n\n\n\n<p>Entonces, \u00bfpodemos ser espirituales sin ser religiosos? \u00bfSon tan diferentes la espiritualidad y la religi\u00f3n? &nbsp;<\/p>\n\n\n\n<p>Este art\u00edculo no pretende definir estos dos t\u00e9rminos ni explicar su aplicaci\u00f3n, sino sintetizarlos y defender la funci\u00f3n tanto de la espiritualidad como de la religi\u00f3n: manifestar la mejor y m\u00e1s aut\u00e9ntica versi\u00f3n de uno mismo en relaci\u00f3n con nuestra fuente divina.<\/p>\n\n\n\n<p>Imagine la experiencia de saltar de un avi\u00f3n con un paraca\u00eddas, comparada con la de ver una serie de fotograf\u00edas. La experiencia es completamente distinta. Sin embargo, si somos sinceros a la hora de aprender sobre el paracaidismo, una foto o un v\u00eddeo son necesarios para que nos hagamos una idea de lo que podemos esperar. La religi\u00f3n se parece mucho a eso, puede parecer pedante, incluso mundana en comparaci\u00f3n con nuestra expectativa de una experiencia espiritual v\u00edvida, pero puede ser esencial para ayudarnos a navegar por las complejidades y trampas de la vida espiritual.<\/p>\n\n\n\n<p>Muchas personas tendr\u00e1n un encuentro divino o una experiencia espiritual a lo largo de su vida y, al intentar transmitir o comprender estos sucesos, algunos de nosotros nos encontraremos viendo la religi\u00f3n, con sus normas y doctrinas formales, como una sombra de aquello que experimentamos. Por eso encontramos la frase cada vez m\u00e1s com\u00fan: \"espiritual pero no religioso\".<ins><\/ins><\/p>\n\n\n\n<p><br>Ser espiritual pero no religioso no te inhabilita para tener pensamientos o creencias religiosas y, de hecho, si tenemos alg\u00fan tipo de experiencia divina y tratamos de interpretar, descifrar y comprender lo que nos ha ocurrido, la religi\u00f3n puede proporcionarnos una vasta base de datos colectiva de comunidad, tradici\u00f3n y pr\u00e1ctica que podemos utilizar para nuestro crecimiento espiritual.<\/p>\n\n\n\n<p>Pero aqu\u00ed radica un peligro, lo que se ha acu\u00f1ado como \"espiritualidad de comida r\u00e1pida\", en la que nos limitamos a elegir del \"men\u00fa espiritual\", la variedad de las llamadas opciones espirituales, dependiendo de c\u00f3mo nos sintamos, con qui\u00e9n estemos, qu\u00e9 hayamos comido ese d\u00eda, etc. Y hoy en d\u00eda, con la opci\u00f3n \"drive through\", ni siquiera necesitamos salir de nuestra propia zona de confort, simplemente nos quedamos en nuestro propio espacio y recogemos nuestra comida. Y hoy en d\u00eda, con la opci\u00f3n \"drive through\", ni siquiera necesitamos salir de nuestra propia zona de confort, simplemente nos quedamos en nuestro propio espacio y recogemos nuestra comida, lo que significa que sin hacer mucho esfuerzo en absoluto, uno puede sentirse \"espiritual\".<\/p>\n\n\n\n<p>Por nuestra cuenta, tenemos muy poca experiencia y objetividad cuando se trata de asuntos espirituales, pero en el contexto de una comunidad o una tradici\u00f3n, nos beneficiamos de un conjunto de experiencias y conocimientos. Sin ese colectivo de informaci\u00f3n, pr\u00e1ctica y comprensi\u00f3n, operamos dentro de nuestra propia perspectiva y suposiciones estrechas, que pueden ser simplemente nuestra propia invenci\u00f3n o una proyecci\u00f3n de nuestras preferencias personales, similar a seleccionar nuestra elecci\u00f3n del men\u00fa de comida r\u00e1pida bas\u00e1ndonos en c\u00f3mo nos sentimos.<\/p>\n\n\n\n<p>Quiero hacer la proposici\u00f3n de que si Dios, lo divino, existe, eso desafiar\u00eda nuestras propias suposiciones y presentar\u00eda cualidades de maneras que ser\u00edan sorprendentes e inesperadas. Sin duda, podemos estar seguros de que algo no es nuestra propia proyecci\u00f3n o invenci\u00f3n si nos encontramos con algo que no es convencionalmente compatible con nuestras propias suposiciones y forma de vivir. <ins><\/ins><\/p>\n\n\n\n<p>No s\u00e9 cu\u00e1les son tus propias creencias y experiencias religiosas, pero desde luego en mi empe\u00f1o por comprender el misterio de la experiencia humana, la religi\u00f3n, en sus diversas formas, ha desafiado sin duda mis suposiciones y preferencias personales, oblig\u00e1ndome a \"pensar fuera de MI caja\". Quiero sugerir que, en el escenario espiritual pero no religioso, no hay nada expl\u00edcito que nos obligue a hacerlo. Y ah\u00ed est\u00e1 el riesgo de que elijamos ideas y creencias que casualmente se ajustan a nuestras preferencias, con lo que no conectamos realmente con algo fuera de nuestro propio yo.<\/p>\n\n\n\n<p>O, para decirlo sin rodeos, puede que s\u00f3lo nos estemos adorando a nosotros mismos, y muy probablemente no sea la versi\u00f3n mejor y m\u00e1s aut\u00e9ntica. Propongo que nos detengamos y apreciemos la noci\u00f3n de que, aunque el \"yo\" es en \u00faltima instancia espiritual, una buena religi\u00f3n desviar\u00e1 nuestra atenci\u00f3n de nuestra propia tendencia y perspectiva ego\u00edstas, hacia algo superior a nosotros mismos, hacia Dios, lo divino, la fuente, as\u00ed como hacia una comunidad de personas, pr\u00e1cticas y tradiciones. <ins><\/ins><\/p>\n\n\n\n<p>Por defecto, somos espirituales, es un s\u00edntoma de nuestro ser, pero la religi\u00f3n es la aplicaci\u00f3n de esa naturaleza intr\u00ednseca, y una necesidad para controlar la mundanidad inherente a nuestra existencia. La pr\u00e1ctica espiritual genuina, la llamemos religi\u00f3n o no, nos permitir\u00e1 elevarnos por encima de nuestro condicionamiento material, para que podamos ser realmente la mejor versi\u00f3n espiritual de nuestro verdadero yo superior, en relaci\u00f3n con nuestra fuente y origen divinos.<\/p>\n\n\n\n<p>Tal vez piense que hay tantas religiones, y cada una de ellas tiene concepciones diferentes que se contradicen. Incluso se matan unas a otras sobre qui\u00e9n es el correcto. Sin embargo, en la pr\u00e1ctica del Bhakti Yoga y la conciencia de Krishna, encontramos una fuerza unificadora que reconcilia todas las contradicciones. El Bhakti divide la realizaci\u00f3n de Dios en 3 aspectos, y todas las pr\u00e1cticas y experiencias espirituales entran en una o en todas las categor\u00edas. Tomemos la analog\u00eda de un tren. Desde lejos, el tren puede parecer s\u00f3lo una luz resplandeciente. Al acercarnos, podemos o\u00edr e incluso ver la forma del tren. Si nos detuvi\u00e9ramos junto al tren o entr\u00e1ramos en \u00e9l, lo ver\u00edamos lleno de pasajeros, cada uno con su propia historia y viaje.<br><br>As\u00ed, en el Bhakti Yoga, comprendemos 3 niveles de realizaci\u00f3n espiritual: Brahman, Paramatma y Bhagavan. Pasamos de una comprensi\u00f3n amplia de lo divino como energ\u00eda universal (la luz del tren - Brahman) a una conciencia de la presencia divina dentro de todas las cosas (el tren mismo aunque sin refinamiento - Paramatma) y finalmente a una relaci\u00f3n personal con el Ser Supremo (el tren completo, con conductor y pasajeros, incluida la luz original - Bhagavan). Esta comprensi\u00f3n hol\u00edstica de lo divino no s\u00f3lo reconcilia las aparentes contradicciones, sino que tambi\u00e9n nos permite conectar m\u00e1s profundamente con lo divino y con los dem\u00e1s. Si quieres saber m\u00e1s sobre este tema, \u00a1ap\u00fantate al curso de Meditaci\u00f3n Mantra, donde se explican estos conceptos con m\u00e1s detalle!<\/p>\n\n\n\n<p>Quiero concluir afirmando que el objetivo y la pr\u00e1ctica de cantar Hare Krishna, aunque pertenecen a la antigua tradici\u00f3n del bhakti yoga, son en s\u00ed mismos espirituales y no religiosos. \u00bfPor qu\u00e9? Porque el objetivo es actuar en la plataforma amorosa espont\u00e1nea del alma o del yo-espiritual, en contraposici\u00f3n a forzarse a uno mismo a seguir reglas y regulaciones debido al deber religioso. Nuestro objetivo es elevarnos por encima de las reglas y los rituales y tener experiencias espirituales genuinas en la plataforma trascendental. \u00bfQuiz\u00e1s hayas experimentado esto de vez en cuando? La tradici\u00f3n del bhakti yoga y el canto de Hare Krishna cuenta con un vasto recurso de comunidad, filosof\u00eda, cultura y tradici\u00f3n de santos, ninguno de los cuales pertenece necesariamente a una (o ninguna) instituci\u00f3n religiosa en particular, que trabajan juntos para preservar y ense\u00f1ar esta pr\u00e1ctica de meditaci\u00f3n con mantras, bhakti yoga, en beneficio de todos los seres vivos.<\/p>\n\n\n\n<p>Del mismo modo que uno puede no conocer los ingredientes de una medicina concreta recetada para curar una enfermedad y, sin embargo, la medicina actuar\u00e1, del mismo modo, a pesar de no conocer el idioma, la pr\u00e1ctica o la herencia del maha mantra Hare Krishna, actuar\u00e1 en beneficio del practicante as\u00ed como de su entorno, y en \u00faltima instancia manifestar\u00e1 la mejor y m\u00e1s aut\u00e9ntica versi\u00f3n de ellos en relaci\u00f3n con su fuente divina, que es la funci\u00f3n tanto de la espiritualidad como de la religi\u00f3n. &nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>\"Dios y el diablo caminaban un d\u00eda por un sendero cuando Dios vio algo que brillaba al lado del camino. Lo cogi\u00f3...<\/p>","protected":false},"author":26,"featured_media":34257,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-34250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","pmpro-has-access",""],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Truth About Being Spiritual But Not Religious: It&#039;s All in Your Head - Chant Now<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chantnow.com\/es\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Truth About Being Spiritual But Not Religious: It&#039;s All in Your Head - Chant Now\" \/>\n<meta property=\"og:description\" content=\"&#8220;God and the devil were walking down a path one day when God spotted something sparkling by the side of the path. Picking it up&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chantnow.com\/es\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/\" \/>\n<meta property=\"og:site_name\" content=\"Chant Now\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-14T07:05:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-14T07:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chantnow.com\/wp-content\/uploads\/2023\/04\/b0ea58a310b74cb811dfbae1a217c1a6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"563\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/\"},\"author\":{\"name\":\"Gita\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/es\\\/#\\\/schema\\\/person\\\/9f69b72f8ae4a7b512cd65e8de43abf2\"},\"headline\":\"The Truth About Being Spiritual But Not Religious: It&#8217;s All in Your Head\",\"datePublished\":\"2023-04-14T07:05:45+00:00\",\"dateModified\":\"2023-04-14T07:19:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/\"},\"wordCount\":1335,\"publisher\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chantnow.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/b0ea58a310b74cb811dfbae1a217c1a6.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/\",\"url\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/\",\"name\":\"The Truth About Being Spiritual But Not Religious: It's All in Your Head - Chant Now\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chantnow.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/b0ea58a310b74cb811dfbae1a217c1a6.jpg\",\"datePublished\":\"2023-04-14T07:05:45+00:00\",\"dateModified\":\"2023-04-14T07:19:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chantnow.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/b0ea58a310b74cb811dfbae1a217c1a6.jpg\",\"contentUrl\":\"https:\\\/\\\/chantnow.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/b0ea58a310b74cb811dfbae1a217c1a6.jpg\",\"width\":563,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chantnow.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Truth About Being Spiritual But Not Religious: It&#8217;s All in Your Head\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/chantnow.com\\\/es\\\/\",\"name\":\"Chant Now\",\"description\":\"Online Bhakti Community\",\"publisher\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chantnow.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/es\\\/#organization\",\"name\":\"Chant Now\",\"url\":\"https:\\\/\\\/chantnow.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chantnow.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/chant-now-logo-circle.png\",\"contentUrl\":\"https:\\\/\\\/chantnow.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/chant-now-logo-circle.png\",\"width\":251,\"height\":251,\"caption\":\"Chant Now\"},\"image\":{\"@id\":\"https:\\\/\\\/chantnow.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/es\\\/#\\\/schema\\\/person\\\/9f69b72f8ae4a7b512cd65e8de43abf2\",\"name\":\"Gita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/chantnow.com\\\/wp-content\\\/uploads\\\/avatars\\\/26\\\/63d504cda324f-bpthumb.png\",\"url\":\"https:\\\/\\\/chantnow.com\\\/wp-content\\\/uploads\\\/avatars\\\/26\\\/63d504cda324f-bpthumb.png\",\"contentUrl\":\"https:\\\/\\\/chantnow.com\\\/wp-content\\\/uploads\\\/avatars\\\/26\\\/63d504cda324f-bpthumb.png\",\"caption\":\"Gita\"},\"url\":\"https:\\\/\\\/chantnow.com\\\/es\\\/author\\\/gitagovinda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La verdad sobre ser espiritual pero no religioso: todo est\u00e1 en tu cabeza - Chant Now","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chantnow.com\/es\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/","og_locale":"es_ES","og_type":"article","og_title":"The Truth About Being Spiritual But Not Religious: It's All in Your Head - Chant Now","og_description":"&#8220;God and the devil were walking down a path one day when God spotted something sparkling by the side of the path. Picking it up&hellip;","og_url":"https:\/\/chantnow.com\/es\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/","og_site_name":"Chant Now","article_published_time":"2023-04-14T07:05:45+00:00","article_modified_time":"2023-04-14T07:19:15+00:00","og_image":[{"width":563,"height":375,"url":"https:\/\/chantnow.com\/wp-content\/uploads\/2023\/04\/b0ea58a310b74cb811dfbae1a217c1a6.jpg","type":"image\/jpeg"}],"author":"Gita","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gita","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/#article","isPartOf":{"@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/"},"author":{"name":"Gita","@id":"https:\/\/chantnow.com\/es\/#\/schema\/person\/9f69b72f8ae4a7b512cd65e8de43abf2"},"headline":"The Truth About Being Spiritual But Not Religious: It&#8217;s All in Your Head","datePublished":"2023-04-14T07:05:45+00:00","dateModified":"2023-04-14T07:19:15+00:00","mainEntityOfPage":{"@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/"},"wordCount":1335,"publisher":{"@id":"https:\/\/chantnow.com\/es\/#organization"},"image":{"@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/#primaryimage"},"thumbnailUrl":"https:\/\/chantnow.com\/wp-content\/uploads\/2023\/04\/b0ea58a310b74cb811dfbae1a217c1a6.jpg","articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/","url":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/","name":"La verdad sobre ser espiritual pero no religioso: todo est\u00e1 en tu cabeza - Chant Now","isPartOf":{"@id":"https:\/\/chantnow.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/#primaryimage"},"image":{"@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/#primaryimage"},"thumbnailUrl":"https:\/\/chantnow.com\/wp-content\/uploads\/2023\/04\/b0ea58a310b74cb811dfbae1a217c1a6.jpg","datePublished":"2023-04-14T07:05:45+00:00","dateModified":"2023-04-14T07:19:15+00:00","breadcrumb":{"@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/#primaryimage","url":"https:\/\/chantnow.com\/wp-content\/uploads\/2023\/04\/b0ea58a310b74cb811dfbae1a217c1a6.jpg","contentUrl":"https:\/\/chantnow.com\/wp-content\/uploads\/2023\/04\/b0ea58a310b74cb811dfbae1a217c1a6.jpg","width":563,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/chantnow.com\/the-truth-about-being-spiritual-but-not-religious-its-all-in-your-head\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chantnow.com\/"},{"@type":"ListItem","position":2,"name":"The Truth About Being Spiritual But Not Religious: It&#8217;s All in Your Head"}]},{"@type":"WebSite","@id":"https:\/\/chantnow.com\/es\/#website","url":"https:\/\/chantnow.com\/es\/","name":"Cantar ahora","description":"Comunidad Bhakti en l\u00ednea","publisher":{"@id":"https:\/\/chantnow.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chantnow.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/chantnow.com\/es\/#organization","name":"Cantar ahora","url":"https:\/\/chantnow.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chantnow.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/chantnow.com\/wp-content\/uploads\/2023\/07\/chant-now-logo-circle.png","contentUrl":"https:\/\/chantnow.com\/wp-content\/uploads\/2023\/07\/chant-now-logo-circle.png","width":251,"height":251,"caption":"Chant Now"},"image":{"@id":"https:\/\/chantnow.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chantnow.com\/es\/#\/schema\/person\/9f69b72f8ae4a7b512cd65e8de43abf2","name":"Gita","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chantnow.com\/wp-content\/uploads\/avatars\/26\/63d504cda324f-bpthumb.png","url":"https:\/\/chantnow.com\/wp-content\/uploads\/avatars\/26\/63d504cda324f-bpthumb.png","contentUrl":"https:\/\/chantnow.com\/wp-content\/uploads\/avatars\/26\/63d504cda324f-bpthumb.png","caption":"Gita"},"url":"https:\/\/chantnow.com\/es\/author\/gitagovinda\/"}]}},"_links":{"self":[{"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/posts\/34250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/comments?post=34250"}],"version-history":[{"count":2,"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/posts\/34250\/revisions"}],"predecessor-version":[{"id":34254,"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/posts\/34250\/revisions\/34254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/media\/34257"}],"wp:attachment":[{"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/media?parent=34250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/categories?post=34250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chantnow.com\/es\/wp-json\/wp\/v2\/tags?post=34250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}